{"id":1008,"date":"2022-01-11T11:19:50","date_gmt":"2022-01-11T10:19:50","guid":{"rendered":"https:\/\/nativery.com\/blog\/?p=1008"},"modified":"2022-01-11T11:36:58","modified_gmt":"2022-01-11T10:36:58","slug":"native-adv-qual-e-il-migliore-widget-per-il-tuo-sito","status":"publish","type":"post","link":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/","title":{"rendered":"Native adv: qual \u00e8 il migliore widget per il tuo sito?"},"content":{"rendered":"\n<p>Se hai scelto di aggiungere spazi native advertising sul tuo sito, hai sicuramente sperimentato la loro efficacia in termini di revenue. Ma hai gi\u00e0 capito qual \u00e8 il migliore widget native per il tuo sito?<\/p>\n\n\n\n<p>I widget nativi, infatti, possono essere vari e ogni tipologia pu\u00f2 aiutarti ad aumentare i guadagni ottenuti dai tuoi spazi pubblicitari.<\/p>\n\n\n\n<p>Iniziamo tuttavia mettendo bene in chiaro una cosa: i widget nativi non corrispondono alla comune descrizione di \u201cwidget\u201d che trovi online.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Widget: distinzioni necessarie<\/strong><\/h2>\n\n\n\n<p>Il termine \u201cwidget\u201d definisce comunemente tutti quegli elementi che forniscono funzionalit\u00e0 aggiuntive ad una pagina web. Sono solitamente presenti all\u2019interno della sidebar e nel footer. Gli esempi pi\u00f9 comuni che avrai sicuramente visto (e implementato) sono: l\u2019elenco delle categorie o dei tag, i moduli di ricerca, l\u2019elenco degli articoli pubblicati di recente.<\/p>\n\n\n\n<p>Insomma, un widget \u00e8 incorporato nella pagina web ospitante e la arricchisce con elementi utili alla sua fruizione.<\/p>\n\n\n\n<p>Nell\u2019advertising online \u2013 ed in particolare nel native advertising \u2013 il termine \u201cwidget\u201d assume un significato molto pi\u00f9 preciso. <strong>Il widget native \u00e8 uno spazio, un box o meglio un posizionamento contenente ads appartenenti alle fonti di traffico native<\/strong>.<\/p>\n\n\n\n<p>Le pubblicit\u00e0, o meglio le ads contenute all\u2019interno dei posizionamenti sono regolate dalla fonte di traffico \u2013 tramite algoritmo o server \u2013 mentre la posizione dei widget nativi sul sito viene decisa dal publisher.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Dove puoi posizionare i widget nativi?<\/strong><\/h2>\n\n\n\n<p>Una volta chiarita la distinzione di significato, entriamo nella pratica delle cose: dove puoi inserire un widget native sul tuo sito?<\/p>\n\n\n\n<p>Anzitutto data la sua natura di posizionamento nativo, il <strong>widget pubblicitario native \u00e8 integrato nel contesto editoriale ospitante in modo camaleontico<\/strong>, diventando uno spazio naturale del tuo sito web.<\/p>\n\n\n\n<p>I posizionamenti pi\u00f9 comuni solitamente sono: <strong>al fondo della pagina web<\/strong>, nella <strong>sidebar<\/strong> e <strong>all\u2019interno dell\u2019articolo<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/nativery-test.ediscomnet.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini.jpg\" alt=\"\" class=\"wp-image-1009\" width=\"418\" height=\"278\" srcset=\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini.jpg 816w, https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini-300x200.jpg 300w, https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini-768x512.jpg 768w, https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini-450x300.jpg 450w, https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1087286450-mini-780x520.jpg 780w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><figcaption>Posizionamento widget<\/figcaption><\/figure><\/div>\n\n\n\n<p>Tuttavia le nuove tecnologie stanno aprendo nuovi orizzonti nativi ancora non esplorati. In pi\u00f9, <a href=\"https:\/\/nativery-test.ediscomnet.com\/blog\/come-va-ladattamento-al-mondo-digitale-cookieless\/\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019avvicinarsi della fine dei cookies di terze parti<\/a> sta spingendo <a href=\"https:\/\/www.nativery.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">le piattaforme native<\/a> a sperimentare nuovi widgets con intelligenza artificiale integrata per arricchire l\u2019esperienza sul sito web.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.nativery.com\/pub.php?\" target=\"_blank\" rel=\"noreferrer noopener\">Contattaci per conoscere i nostri nuovi widgets per il tuo sito!<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Quanta pubblicit\u00e0 contiene un widget native?<\/strong><\/h2>\n\n\n\n<p>Il widget native \u00e8 come un <strong>contenitore di ads camaleontiche<\/strong>, integrate alla perfezione nel contesto editoriale ospitante. Non solo, le pubblicit\u00e0 presenti all\u2019interno del widget, poich\u00e9 derivanti da traffico nativo, <strong>soddisfano le preferenze degli utenti del sito<\/strong>.<\/p>\n\n\n\n<p>In altre parole, un widget nativo di un sito di giardinaggio conterr\u00e0 preferibilmente delle ads relative all\u2019hobby green: contenuti sponsorizzati di e-commerce di fiori, bricolage e simili.<\/p>\n\n\n\n<p>Ma quanta pubblicit\u00e0 pu\u00f2 contenere un widget native? Come publisher, puoi decidere tu quante ads inserire nel widget: una, due, tre fino ad arrivare a box contenenti fino a sedici ads sottoforma di contenuti consigliati. Alcune piattaforme native, inoltre, forniscono un widget nativo \u201cinfinite scroll\u201d, ovvero una lista continua e aggiornata di ads a fondo pagina.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qual \u00e8 il migliore widget per il tuo sito?<\/strong><\/h2>\n\n\n\n<p>La domanda sorge spontanea quando si devono assegnare gli spazi del sito. Il nostro consiglio \u00e8 quello di analizzare il proprio traffico e gli insight per valutare il comportamento degli utenti e scegliere un posizionamento nativo in linea con le loro preferenze.<\/p>\n\n\n\n<p>Inoltre, ti consigliamo di confrontarti con un <strong>account specializzato<\/strong> della piattaforma native che hai scelto per orientarti meglio. Infine, ricorda che un <strong>supporto di uno specialista native<\/strong> \u00e8 un valore aggiunto all\u2019attivit\u00e0 di advertising. Potrai accedere a nuovi posizionamenti nativi e testare sempre nuove modalit\u00e0 di advertising pi\u00f9 remunerative della classica pubblicit\u00e0 display.<\/p>\n\n\n\n<p>Che cosa aspetti ad implementare il widget nativo sul tuo sito?<\/p>\n\n\n\n<p><a href=\"https:\/\/www.nativery.com\/index.php?{ignore}#contact\" target=\"_blank\" rel=\"noreferrer noopener\">Contattaci!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se hai scelto di aggiungere spazi native advertising sul tuo sito, hai sicuramente sperimentato la loro efficacia in termini di revenue. Ma hai gi\u00e0 capito qual \u00e8 il migliore widget native per il tuo sito? I widget nativi, infatti, possono essere vari e ogni tipologia pu\u00f2 aiutarti ad aumentare i guadagni ottenuti dai tuoi spazi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1012,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[63,59],"class_list":{"0":"post-1008","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo-native","8":"tag-adv-e-mkt-strategy","9":"tag-publisher"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog<\/title>\n<meta name=\"description\" content=\"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog\" \/>\n<meta property=\"og:description\" content=\"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/\" \/>\n<meta property=\"og:site_name\" content=\"Nativery Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-11T10:19:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-11T10:36:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martina Solei\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martina Solei\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/\",\"url\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/\",\"name\":\"Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg\",\"datePublished\":\"2022-01-11T10:19:50+00:00\",\"dateModified\":\"2022-01-11T10:36:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/98be303926dfe50e2e8e31578cea6730\"},\"description\":\"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage\",\"url\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg\",\"contentUrl\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg\",\"width\":1000,\"height\":582,\"caption\":\"migliore widget native\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nativery.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Native adv: qual \u00e8 il migliore widget per il tuo sito?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#website\",\"url\":\"https:\/\/www.nativery.com\/blog\/\",\"name\":\"Nativery Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nativery.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/98be303926dfe50e2e8e31578cea6730\",\"name\":\"Martina Solei\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cf1b110c632e0d1db05163bc93a43286?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cf1b110c632e0d1db05163bc93a43286?s=96&d=mm&r=g\",\"caption\":\"Martina Solei\"},\"url\":\"https:\/\/www.nativery.com\/blog\/author\/martina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog","description":"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/","og_locale":"it_IT","og_type":"article","og_title":"Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog","og_description":"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?","og_url":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/","og_site_name":"Nativery Blog","article_published_time":"2022-01-11T10:19:50+00:00","article_modified_time":"2022-01-11T10:36:58+00:00","og_image":[{"width":1000,"height":582,"url":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg","type":"image\/jpeg"}],"author":"Martina Solei","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Martina Solei","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/","url":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/","name":"Native adv: qual \u00e8 il migliore widget per il tuo sito? - Nativery Blog","isPartOf":{"@id":"https:\/\/www.nativery.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage"},"image":{"@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg","datePublished":"2022-01-11T10:19:50+00:00","dateModified":"2022-01-11T10:36:58+00:00","author":{"@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/98be303926dfe50e2e8e31578cea6730"},"description":"I widget nativi incorporano ads che aumentano le revenue pubblicitarie di un sito. Come scegliere il migliore widget native per il tuo sito?","breadcrumb":{"@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#primaryimage","url":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg","contentUrl":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2022\/01\/shutterstock_1414487423-mini.jpg","width":1000,"height":582,"caption":"migliore widget native"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nativery.com\/blog\/native-adv-qual-e-il-migliore-widget-per-il-tuo-sito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nativery.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Native adv: qual \u00e8 il migliore widget per il tuo sito?"}]},{"@type":"WebSite","@id":"https:\/\/www.nativery.com\/blog\/#website","url":"https:\/\/www.nativery.com\/blog\/","name":"Nativery Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nativery.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/98be303926dfe50e2e8e31578cea6730","name":"Martina Solei","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cf1b110c632e0d1db05163bc93a43286?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf1b110c632e0d1db05163bc93a43286?s=96&d=mm&r=g","caption":"Martina Solei"},"url":"https:\/\/www.nativery.com\/blog\/author\/martina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/1008"}],"collection":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/comments?post=1008"}],"version-history":[{"count":3,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/1008\/revisions"}],"predecessor-version":[{"id":1013,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/1008\/revisions\/1013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/media\/1012"}],"wp:attachment":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/media?parent=1008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/categories?post=1008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/tags?post=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}