{"id":920,"date":"2021-09-15T12:00:36","date_gmt":"2021-09-15T10:00:36","guid":{"rendered":"https:\/\/nativery.com\/blog\/?p=920"},"modified":"2021-09-22T12:56:22","modified_gmt":"2021-09-22T10:56:22","slug":"scalabilita-massimizza-risultati","status":"publish","type":"post","link":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/","title":{"rendered":"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising"},"content":{"rendered":"\n<p>Hai attivato una campagna native, stai scalando bene il mercato e raccogli ottimi frutti. Con il tempo per\u00f2 il raccolto ha iniziato a diventare leggermente pi\u00f9 magro. Non preoccuparti, \u00e8 tutto ok!<\/p>\n\n\n\n<p>Nel mondo dell\u2019advertising <strong>\u00e8 perfettamente normale che una campagna, passato un po\u2019 di tempo dalla messa online, inizi a diminuire gradualmente le sue performance<\/strong>.<\/p>\n\n\n\n<p>I motivi sono vari e varie sono le soluzioni per continuare ad avere ottime performance con una campagna native \u201cstorica\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Abbassamento performances: principali fattori<\/strong><\/h2>\n\n\n\n<p><em><strong>Ad fatigue<\/strong><\/em><\/p>\n\n\n\n<p>Uno dei primi grandi problemi online \u00e8 l\u2019ad fatigue. In fase di programmazione di una campagna native, infatti, si definisce una specifica target audience a cui si vuole arrivare e a cui si mostrer\u00e0 maggiormente l\u2019annuncio pubblicitario.<\/p>\n\n\n\n<p>Con il passare del tempo \u00e8 normale che gli stessi utenti a target a cui vuoi arrivare saranno gi\u00e0 stati esposti al tuo annuncio e avranno probabilmente gi\u00e0 interagito con il tuo brand.<\/p>\n\n\n\n<p>A mano a mano che il tuo pubblico target compie azioni di conversione sulla tua campagna \u00e8 perfettamente normale che il CTR (Click-Through-Rate) si abbassi: pi\u00f9 gli annunci adv restano uguali, maggiore sar\u00e0 il calo del tasso di conversione.<\/p>\n\n\n\n<p><em><strong>Raggiungimento dell\u2019audience completata<\/strong><\/em><\/p>\n\n\n\n<p>Un altro fattore da considerare nella diminuzione delle performance \u00e8 il raggiungimento totale del target pi\u00f9 ricettivo. Non appena la campagna viene messa online, infatti, l\u2019audience preferita dal tuo business viene subito esposta agli annunci.<\/p>\n\n\n\n<p>Date le caratteristiche dell\u2019annuncio a target gli utenti, molto probabilmente, completeranno la conversione subito o nei giorni successivi alla primissima esposizione all\u2019annuncio.<\/p>\n\n\n\n<p>Se hai agito su pi\u00f9 audience simili il discorso \u00e8 lo stesso: molto probabilmente un utente non interagir\u00e0 con un annuncio con cui ha completato un\u2019azione, anche se questo \u00e8 accattivante e costruito apposta sulle sue preferenze.<\/p>\n\n\n\n<p><em><strong>Competitors sempre in agguato<\/strong><\/em><\/p>\n\n\n\n<p>Il mondo online \u00e8 una jungla piena di predatori, ricorda! Se vuoi scalare un qualsiasi mercato devi prima o poi fare i conti con l\u2019inevitabile competitivit\u00e0.<\/p>\n\n\n\n<p>La concorrenza di mercato \u00e8 uno dei principali fattori che determinano un abbassamento delle performance per gli advertisers.<\/p>\n\n\n\n<p>Non \u00e8 affatto raro, infatti, constatare un calo del CTR di una campagna pubblicitaria online del 20%-30% quando un importante competitor entra nello stesso mercato advertising.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Soluzioni di scalabilit\u00e0 per avere performance ottimali<\/strong><\/h2>\n\n\n\n<p>Dopo aver presentato i fattori pi\u00f9 amari ecco in arrivo una dose necessaria di zuccheri. <strong>Nell\u2019advertising online nulla \u00e8 mai davvero perduto!<\/strong><\/p>\n\n\n\n<p><strong>Scalare il mercato con una campagna<\/strong> che sembra gi\u00e0 aver dato tutti i suoi frutti <strong>\u00e8 perfettamente possibile<\/strong>, basta ovviamente <strong>analizzare i dati, ottimizzare e, soprattutto, testare<\/strong>.<\/p>\n\n\n\n<p>Le <strong>soluzioni <\/strong>che puoi applicare alle problematiche sopracitate <strong>sono principalmente tre<\/strong>, strettamente correlate tra loro e <strong>utilizzabili in maniera integrata<\/strong>.<\/p>\n\n\n\n<p><em><strong>Scalabilit\u00e0 Verticale<\/strong><\/em><\/p>\n\n\n\n<p>Con la scalabilit\u00e0 verticale resti all\u2019interno della tua nicchia di mercato e opti per incrementare alcune caratteristiche dell\u2019offerta veicolata.<\/p>\n\n\n\n<p>Nell\u2019advertising online mantieni la stessa campagna pubblicitaria che funziona bene per l\u2019audience target a cui ti eri rivolto in prima battuta. Tuttavia, per stimolare nuove conversioni occorre rivedere alcuni elementi dell\u2019offerta e del budget della campagna.<\/p>\n\n\n\n<p>In particolare, <strong>con la scalabilit\u00e0 verticale ci riferiamo a<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Aumentare il budget assegnato alla campagna native del 10%-20%<\/strong><\/li><li><strong>Aumentare il bid <\/strong>(l\u2019offerta a base d\u2019asta) <strong>della campagna e dei widget<\/strong><\/li><li><strong>Ottimizzare gli annunci nativi inserendo anche nuove promozioni dedicate<\/strong><\/li><li><strong>Monitorare costantemente l\u2019andamento<\/strong><\/li><\/ul>\n\n\n\n<p><em><strong>Scalabilit\u00e0 Orizzontale<\/strong><\/em><\/p>\n\n\n\n<p>Quando vuoi scalare orizzontalmente un mercato vai ad agire su alcuni fattori in comune con il precedente metodo, aggiungendo degli elementi strategici.<\/p>\n\n\n\n<p>Con la <strong>scalabilit\u00e0 orizzontale puoi testare tutti quei nuovi fattori<\/strong> che possono rigenerare le conversioni avute nel primo periodo di campagna.<\/p>\n\n\n\n<p>In particolare, puoi effettuare test su:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Nuovi publishers<\/strong><\/li><li><strong>Verticals che possono avere all\u2019interno un\u2019audience simile a quella pi\u00f9 ricettiva al prodotto sponsorizzato<\/strong><\/li><li><strong>Cambiare i titoli degli annunci e nuovi metodi di conversione <\/strong>(ad esempio, inserire un elemento accattivante per l\u2019utente, come un gioco o una prova virtuale)<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ottimizzare le creativit\u00e0 periodicamente<\/strong><\/h2>\n\n\n\n<p>In ultimo ma non per importanza, il fil rouge che corre tra i due metodi sopracitati \u00e8 il rinnovamento delle creativit\u00e0 veicolate online.<\/p>\n\n\n\n<p>Esattamente come un cartellone pubblicitario stradale, anche un adv online perde il suo smalto dopo qualche tempo. Dovrai occuparti, quindi, di rinnovarne la grafica e i copy una volta che hanno esaurito la loro potenza di fuoco.<\/p>\n\n\n\n<p>Ci\u00f2 non significa apportare modifiche quotidiane, ma puoi adottare una strategia che permetta di modificare gli elementi creativi a seconda di differenti fattori: stagionalit\u00e0, festivit\u00e0, eventi mondiali e simili.<\/p>\n\n\n\n<p>Insomma, le campagne native possono essere delle evergreen. Esattamente come le piante, per\u00f2, hanno bisogno di cura e attenzioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hai attivato una campagna native, stai scalando bene il mercato e raccogli ottimi frutti. Con il tempo per\u00f2 il raccolto ha iniziato a diventare leggermente pi\u00f9 magro. Non preoccuparti, \u00e8 tutto ok! Nel mondo dell\u2019advertising \u00e8 perfettamente normale che una campagna, passato un po\u2019 di tempo dalla messa online, inizi a diminuire gradualmente le sue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":921,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[63,60],"class_list":{"0":"post-920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo-native","8":"tag-adv-e-mkt-strategy","9":"tag-advertiser"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog\" \/>\n<meta property=\"og:description\" content=\"Hai attivato una campagna native, stai scalando bene il mercato e raccogli ottimi frutti. Con il tempo per\u00f2 il raccolto ha iniziato a diventare leggermente pi\u00f9 magro. Non preoccuparti, \u00e8 tutto ok! Nel mondo dell\u2019advertising \u00e8 perfettamente normale che una campagna, passato un po\u2019 di tempo dalla messa online, inizi a diminuire gradualmente le sue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/\" \/>\n<meta property=\"og:site_name\" content=\"Nativery Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T10:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T10:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alessia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"alessia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/\",\"url\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/\",\"name\":\"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg\",\"datePublished\":\"2021-09-15T10:00:36+00:00\",\"dateModified\":\"2021-09-22T10:56:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/d4142732619920706e2dbaec9bbb281e\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage\",\"url\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg\",\"contentUrl\":\"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg\",\"width\":2560,\"height\":1340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nativery.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#website\",\"url\":\"https:\/\/www.nativery.com\/blog\/\",\"name\":\"Nativery Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nativery.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/d4142732619920706e2dbaec9bbb281e\",\"name\":\"alessia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0706e041f1dcf883b1589e38c62e63c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0706e041f1dcf883b1589e38c62e63c3?s=96&d=mm&r=g\",\"caption\":\"alessia\"},\"sameAs\":[\"https:\/\/nativery-test.ediscomnet.com\/blog\"],\"url\":\"https:\/\/www.nativery.com\/blog\/author\/alessia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/","og_locale":"it_IT","og_type":"article","og_title":"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog","og_description":"Hai attivato una campagna native, stai scalando bene il mercato e raccogli ottimi frutti. Con il tempo per\u00f2 il raccolto ha iniziato a diventare leggermente pi\u00f9 magro. Non preoccuparti, \u00e8 tutto ok! Nel mondo dell\u2019advertising \u00e8 perfettamente normale che una campagna, passato un po\u2019 di tempo dalla messa online, inizi a diminuire gradualmente le sue [&hellip;]","og_url":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/","og_site_name":"Nativery Blog","article_published_time":"2021-09-15T10:00:36+00:00","article_modified_time":"2021-09-22T10:56:22+00:00","og_image":[{"width":2560,"height":1340,"url":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg","type":"image\/jpeg"}],"author":"alessia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"alessia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/","url":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/","name":"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising - Nativery Blog","isPartOf":{"@id":"https:\/\/www.nativery.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage"},"image":{"@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg","datePublished":"2021-09-15T10:00:36+00:00","dateModified":"2021-09-22T10:56:22+00:00","author":{"@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/d4142732619920706e2dbaec9bbb281e"},"breadcrumb":{"@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#primaryimage","url":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg","contentUrl":"https:\/\/www.nativery.com\/blog\/wp-content\/uploads\/2021\/09\/shutterstock_1946840386-scaled.jpg","width":2560,"height":1340},{"@type":"BreadcrumbList","@id":"https:\/\/www.nativery.com\/blog\/scalabilita-massimizza-risultati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nativery.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Scalabilit\u00e0: come massimizzare i risultati di una campagna native advertising"}]},{"@type":"WebSite","@id":"https:\/\/www.nativery.com\/blog\/#website","url":"https:\/\/www.nativery.com\/blog\/","name":"Nativery Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nativery.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/d4142732619920706e2dbaec9bbb281e","name":"alessia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.nativery.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0706e041f1dcf883b1589e38c62e63c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0706e041f1dcf883b1589e38c62e63c3?s=96&d=mm&r=g","caption":"alessia"},"sameAs":["https:\/\/nativery-test.ediscomnet.com\/blog"],"url":"https:\/\/www.nativery.com\/blog\/author\/alessia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/920"}],"collection":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/comments?post=920"}],"version-history":[{"count":4,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/920\/revisions"}],"predecessor-version":[{"id":926,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/posts\/920\/revisions\/926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/media\/921"}],"wp:attachment":[{"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/media?parent=920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/categories?post=920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nativery.com\/blog\/wp-json\/wp\/v2\/tags?post=920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}